{"id":7520,"date":"2025-01-20T10:55:55","date_gmt":"2025-01-20T10:55:55","guid":{"rendered":"https:\/\/new.ppaf.ch\/?p=7520"},"modified":"2025-01-20T10:55:55","modified_gmt":"2025-01-20T10:55:55","slug":"pierre-yves-massot","status":"publish","type":"post","link":"https:\/\/ppaf.ch\/de\/pierre-yves-massot\/","title":{"rendered":"Pierre-Yves Massot"},"content":{"rendered":"<p>Aufrichtigkeit, Respekt, Engagement und eine unstillbare Neugier auf die Welt sind die markantesten Aspekte in der Arbeit von Pierre-Yves Massot.<\/p>\n\n\n\n<p>Diese Neugier f\u00fchrte sie zu drei bedeutenden sechsmonatigen Aufenthalten: 2003 in Russland, 2005 in Brasilien und 2014 in Berlin.<\/p>\n\n\n\n<p>Die gleiche Neugier lie\u00df sie zwischen 2009 und 2013 Soziologie und Kunstgeschichte an der Universit\u00e4t Freiburg studieren, was ihr neue Werkzeuge und Interessen er\u00f6ffnete, die ihren fotografischen Ansatz heute bereichern.<\/p>\n\n\n\n<p>Pierre-Yves Massot war 2015 au\u00dferdem ein Jahr lang Fotochef eines Schweizer Magazins (Sept), was ihm die M\u00f6glichkeit gab, sich f\u00fcr die Produktion anderer Fotografen einzusetzen und seine Verbundenheit mit der Arbeit von Autoren zu st\u00e4rken.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Sinc\u00e9rit\u00e9, respect, engagement et une curiosit\u00e9 insatiable&nbsp;pour le monde sont les aspects les plus marquants dans le travail de Pierre-Yves Massot. Cette curiosit\u00e9 l\u2019a men\u00e9e a faire trois s\u00e9jours significatifs de six mois: un en Russie en 2003, un autre au Br\u00e9sil en 2005 et enfin un dernier \u00e0 Berlin en 2014. Cette m\u00eame curiosit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7521,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22],"tags":[5,6,7,11,13,14,15,16,17],"class_list":["post-7520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-photographe","tag-architecture","tag-artistique","tag-evenementiel","tag-nature","tag-portrait","tag-presse","tag-produits","tag-reportage","tag-video"],"acf":[],"_links":{"self":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/7520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/comments?post=7520"}],"version-history":[{"count":1,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/7520\/revisions"}],"predecessor-version":[{"id":7527,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/7520\/revisions\/7527"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media\/7521"}],"wp:attachment":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media?parent=7520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/categories?post=7520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/tags?post=7520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}