{"id":6623,"date":"2024-06-10T15:34:11","date_gmt":"2024-06-10T13:34:11","guid":{"rendered":"https:\/\/ppaf.ch\/?p=6623"},"modified":"2025-02-12T12:33:26","modified_gmt":"2025-02-12T12:33:26","slug":"emmanuel-gavillet-mur-blanc-13","status":"publish","type":"post","link":"https:\/\/ppaf.ch\/de\/emmanuel-gavillet-mur-blanc-13\/","title":{"rendered":"Seganova: Emmanuel Gavillet begibt sich auf die Spuren der Saane"},"content":{"rendered":"<p>Das 2021 begonnene Projekt \u00abSeganova\u00bb (Sarine auf Gallisch bedeutet \u00abLa Forte\u00bb) ist eine ehrgeizige fotografische Leistung.<\/p>\n\n\n\n<p>Emmanuel Gavillet folgt dem Fluss seit seiner Quelle am Sanetsch. Die ersten Aufnahmen, die exklusiv auf der Wei\u00dfen Mauer pr\u00e4sentiert werden, konfrontieren das Publikum mit imposanten Mineral- und Pflanzendekorationen. Die Saane h\u00e4lt sich diskret zur\u00fcck. Man erkennt nur ihr Werk, das sie im Laufe der Zeit vollbracht hat.  Die Herausforderung besteht darin, den gesamten Flusslauf von seinen ruhigen Ufern bis zu den tiefen, zerkl\u00fcfteten Schluchten zu durchqueren und Schwarz-Wei\u00df-Bilder in geografischen Abschnitten zu sammeln.<\/p>\n\n\n\n<p>Emmanuel Gavillet begann seine Laufbahn an der Schule f\u00fcr angewandte Kunst in Vevey. Nach seinem Diplom als Fotograf trat er in das Labor Diaprint SA ein, das er heute leitet. Als Entdecker mit Leib und Seele realisierte er verschiedene fotografische Arbeiten in Norwegen und Island. Seine Serie Gastlosen, die er mit einer gro\u00dfformatigen Kamera realisierte, wurde 2010 ver\u00f6ffentlicht und im Mus\u00e9e gru\u00e9rien ausgestellt.&nbsp;&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>D\u00e9but\u00e9 en 2021, le projet \u00ab&nbsp;Seganova&nbsp;\u00bb (Sarine en gaulois signifie \u00ab&nbsp;La Forte&nbsp;\u00bb) est une r\u00e9alisation photographique ambitieuse. Emmanuel Gavillet suit la rivi\u00e8re depuis sa source au Sanetsch. Les premiers clich\u00e9s pr\u00e9sent\u00e9s en exclusivit\u00e9 sur le Mur blanc confrontent le public \u00e0 d\u2019imposants d\u00e9cors min\u00e9raux et v\u00e9g\u00e9taux. La Sarine s\u2019y fait discr\u00e8te. On ne distingue que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7023,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-6623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/comments?post=6623"}],"version-history":[{"count":5,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6623\/revisions"}],"predecessor-version":[{"id":8907,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6623\/revisions\/8907"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media\/7023"}],"wp:attachment":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media?parent=6623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/categories?post=6623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/tags?post=6623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}