{"id":6249,"date":"2021-06-22T11:07:16","date_gmt":"2021-06-22T09:07:16","guid":{"rendered":"https:\/\/ppaf.ch\/?p=6249"},"modified":"2025-02-13T21:53:34","modified_gmt":"2025-02-13T21:53:34","slug":"mur-blanc-5-nicolas-repond","status":"publish","type":"post","link":"https:\/\/ppaf.ch\/de\/mur-blanc-5-nicolas-repond\/","title":{"rendered":"Ein Sprung in den Pool von Bulle mit Nicolas Repond"},"content":{"rendered":"<p><strong>Nicolas Repond wurde von der Stadt Bulle beauftragt, den Umbau des Schwimmbads zwischen 2020 und 2021 fotografisch zu begleiten, und zwar vor, w\u00e4hrend und nach den Arbeiten. Zwei Dinge fallen auf, wenn man die Bilder entdeckt, die das alte Schwimmbad vor seiner Schlie\u00dfung im Jahr 2020 zeigen.<\/strong><\/p>\n\n\n\n<p>Da ist zun\u00e4chst einmal die Aufmerksamkeit f\u00fcr die Menschen - die Stammg\u00e4ste, das Personal, die bunte und laute Menge der Badenden und Schwimmenden, das fr\u00f6hliche Durcheinander der Planschbecken, die Konzentration der Schwimmer pro Kilometer, kurz gesagt, die ausufernde Soziologie der Bev\u00f6lkerungsgruppen, die im Laufe der Zeit die Becken besuchten. Seit seinen Anf\u00e4ngen im Jahr 1918 hatte das Schwimmbad in der N\u00e4he des Arbeiterviertels der Rue Sciob\u00e9ret eine volkst\u00fcmliche Berufung, die es bis heute beibehalten hat. Dies spiegelt sich in den Bildern des Fotografen wider.<\/p>\n\n\n\n<p>Zweitens und auf subtilere Weise hat sich Nicolas Repond f\u00fcr die Umgebung, die Bauten und die Beschilderung interessiert, die das Baden einrahmen. Er zeichnet ein scharfsinniges und manchmal ironisches Portr\u00e4t. \u00dcber den urspr\u00fcnglichen Auftrag - die \u00dcberwachung einer Baustelle - hinaus zeigt der Fotograf auch die Beziehungen, die zwischen einem Ort und seinen Nutzern gekn\u00fcpft werden. Er ber\u00fchrt mit dem Finger die tiefe Identit\u00e4t dieses so banalen und doch so besonderen Ortes.<\/p>\n\n\n\n<p>Das Schwimmbad ist eine geschlossene Welt, die vom Rest der Stadt durch ein ganzes Programm von Trennw\u00e4nden, Mauern, Toren und Baumhecken abgetrennt ist, deren Hauptfunktion darin besteht, die (teilweise) entbl\u00f6\u00dften K\u00f6rper der Benutzer vor den Augen der Passanten zu verbergen. Wir betreten das Geb\u00e4ude gemeinsam mit dem Fotografen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nicolas Repond wurde im Auftrag der Stadt<br \/>\nBulle, um eine fotografische \u00dcberwachung der<br \/>\nUmbauten des Schwimmbads zwischen 2020 und 2021,<br \/>\nvor, w\u00e4hrend und nach der Arbeit. Zwei Dinge<br \/>\nschlagen ein, wenn sie die Bilder entdecken, die zeigen<br \/>\ndas alte Schwimmbad, bevor es 2020 geschlossen wird...<\/p>","protected":false},"author":1,"featured_media":9082,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[23],"tags":[],"class_list":["post-6249","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"_links":{"self":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/comments?post=6249"}],"version-history":[{"count":2,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6249\/revisions"}],"predecessor-version":[{"id":9083,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/posts\/6249\/revisions\/9083"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media\/9082"}],"wp:attachment":[{"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/media?parent=6249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/categories?post=6249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppaf.ch\/de\/wp-json\/wp\/v2\/tags?post=6249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}